{"id":1315,"date":"2023-09-24T12:54:26","date_gmt":"2023-09-24T12:54:26","guid":{"rendered":"http:\/\/www.d-paideia.eu\/wp-content\/uploads\/2023\/09\/Poster-A3_1.jpg"},"modified":"2024-09-27T08:35:52","modified_gmt":"2024-09-27T08:35:52","slug":"poster-a3_1-2","status":"inherit","type":"attachment","link":"https:\/\/www.d-paideia.eu\/it\/poster-a3_1-2\/","title":{"rendered":"Poster A3_1"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"class_list":["post-1315","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.d-paideia.eu\/wp-content\/uploads\/2023\/09\/Poster-A3_1-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"212\" height=\"300\" src=\"https:\/\/www.d-paideia.eu\/wp-content\/uploads\/2023\/09\/Poster-A3_1-212x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1810,"height":2560,"file":"2023\/09\/Poster-A3_1-scaled.jpg","filesize":600610,"sizes":{"medium":{"file":"Poster-A3_1-212x300.jpg","width":212,"height":300,"filesize":17306,"mime_type":"image\/jpeg","source_url":"https:\/\/www.d-paideia.eu\/wp-content\/uploads\/2023\/09\/Poster-A3_1-212x300.jpg"},"large":{"file":"Poster-A3_1-724x1024.jpg","width":724,"height":1024,"filesize":138836,"mime_type":"image\/jpeg","source_url":"https:\/\/www.d-paideia.eu\/wp-content\/uploads\/2023\/09\/Poster-A3_1-724x1024.jpg"},"thumbnail":{"file":"Poster-A3_1-150x150.jpg","width":150,"height":150,"filesize":7102,"mime_type":"image\/jpeg","source_url":"https:\/\/www.d-paideia.eu\/wp-content\/uploads\/2023\/09\/Poster-A3_1-150x150.jpg"},"medium_large":{"file":"Poster-A3_1-768x1086.jpg","width":768,"height":1086,"filesize":154025,"mime_type":"image\/jpeg","source_url":"https:\/\/www.d-paideia.eu\/wp-content\/uploads\/2023\/09\/Poster-A3_1-768x1086.jpg"},"1536x1536":{"file":"Poster-A3_1-1086x1536.jpg","width":1086,"height":1536,"filesize":272025,"mime_type":"image\/jpeg","source_url":"https:\/\/www.d-paideia.eu\/wp-content\/uploads\/2023\/09\/Poster-A3_1-1086x1536.jpg"},"2048x2048":{"file":"Poster-A3_1-1448x2048.jpg","width":1448,"height":2048,"filesize":424614,"mime_type":"image\/jpeg","source_url":"https:\/\/www.d-paideia.eu\/wp-content\/uploads\/2023\/09\/Poster-A3_1-1448x2048.jpg"},"et-pb-post-main-image":{"file":"Poster-A3_1-400x250.jpg","width":400,"height":250,"filesize":22919,"mime_type":"image\/jpeg","source_url":"https:\/\/www.d-paideia.eu\/wp-content\/uploads\/2023\/09\/Poster-A3_1-400x250.jpg"},"et-pb-post-main-image-fullwidth":{"file":"Poster-A3_1-1080x675.jpg","width":1080,"height":675,"filesize":129781,"mime_type":"image\/jpeg","source_url":"https:\/\/www.d-paideia.eu\/wp-content\/uploads\/2023\/09\/Poster-A3_1-1080x675.jpg"},"et-pb-portfolio-image":{"file":"Poster-A3_1-400x284.jpg","width":400,"height":284,"filesize":26445,"mime_type":"image\/jpeg","source_url":"https:\/\/www.d-paideia.eu\/wp-content\/uploads\/2023\/09\/Poster-A3_1-400x284.jpg"},"et-pb-portfolio-module-image":{"file":"Poster-A3_1-510x382.jpg","width":510,"height":382,"filesize":43766,"mime_type":"image\/jpeg","source_url":"https:\/\/www.d-paideia.eu\/wp-content\/uploads\/2023\/09\/Poster-A3_1-510x382.jpg"},"et-pb-portfolio-image-single":{"file":"Poster-A3_1-1080x1527.jpg","width":1080,"height":1527,"filesize":269281,"mime_type":"image\/jpeg","source_url":"https:\/\/www.d-paideia.eu\/wp-content\/uploads\/2023\/09\/Poster-A3_1-1080x1527.jpg"},"et-pb-gallery-module-image-portrait":{"file":"Poster-A3_1-400x516.jpg","width":400,"height":516,"filesize":46970,"mime_type":"image\/jpeg","source_url":"https:\/\/www.d-paideia.eu\/wp-content\/uploads\/2023\/09\/Poster-A3_1-400x516.jpg"},"et-pb-post-main-image-fullwidth-large":{"file":"Poster-A3_1-1920x1800.jpg","width":1920,"height":1800,"filesize":514646,"mime_type":"image\/jpeg","source_url":"https:\/\/www.d-paideia.eu\/wp-content\/uploads\/2023\/09\/Poster-A3_1-1920x1800.jpg"},"et-pb-image--responsive--desktop":{"file":"Poster-A3_1-1280x1810.jpg","width":1280,"height":1810,"filesize":350667,"mime_type":"image\/jpeg","source_url":"https:\/\/www.d-paideia.eu\/wp-content\/uploads\/2023\/09\/Poster-A3_1-1280x1810.jpg"},"et-pb-image--responsive--tablet":{"file":"Poster-A3_1-980x1386.jpg","width":980,"height":1386,"filesize":229604,"mime_type":"image\/jpeg","source_url":"https:\/\/www.d-paideia.eu\/wp-content\/uploads\/2023\/09\/Poster-A3_1-980x1386.jpg"},"et-pb-image--responsive--phone":{"file":"Poster-A3_1-480x679.jpg","width":480,"height":679,"filesize":68782,"mime_type":"image\/jpeg","source_url":"https:\/\/www.d-paideia.eu\/wp-content\/uploads\/2023\/09\/Poster-A3_1-480x679.jpg"},"full":{"file":"Poster-A3_1-scaled.jpg","width":1810,"height":2560,"mime_type":"image\/jpeg","source_url":"https:\/\/www.d-paideia.eu\/wp-content\/uploads\/2023\/09\/Poster-A3_1-scaled.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"original_image":"Poster-A3_1.jpg"},"post":null,"source_url":"https:\/\/www.d-paideia.eu\/wp-content\/uploads\/2023\/09\/Poster-A3_1-scaled.jpg","filename":"Poster-A3_1.jpg","filesize":600610,"_links":{"self":[{"href":"https:\/\/www.d-paideia.eu\/it\/wp-json\/wp\/v2\/media\/1315","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.d-paideia.eu\/it\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.d-paideia.eu\/it\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.d-paideia.eu\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.d-paideia.eu\/it\/wp-json\/wp\/v2\/comments?post=1315"}]}}